{"id":4433,"date":"2024-07-09T08:50:33","date_gmt":"2024-07-09T12:50:33","guid":{"rendered":"https:\/\/www.gcmenvirosynergies.com\/?page_id=4433"},"modified":"2025-07-21T15:04:12","modified_gmt":"2025-07-21T19:04:12","slug":"ecology-and-natural-environments","status":"publish","type":"page","link":"https:\/\/www.gcmenvirosynergies.com\/en\/services\/ecologie-et-milieux-naturels\/","title":{"rendered":"Ecology and natural environments"},"content":{"rendered":"<style>.kb-row-layout-id4433_4474e0-51 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4433_4474e0-51 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4433_4474e0-51 > .kt-row-column-wrap{column-gap:80px;row-gap:20px;max-width:var( --global-content-width, 1440px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4433_4474e0-51 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4433_4474e0-51 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4433_4474e0-51 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id4433_4474e0-51 alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4433_a83428-7d > .kt-inside-inner-col{display:flex;}.kadence-column4433_a83428-7d > .kt-inside-inner-col,.kadence-column4433_a83428-7d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_a83428-7d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_a83428-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_a83428-7d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4433_a83428-7d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_a83428-7d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_a83428-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_a83428-7d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_a83428-7d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4433_a83428-7d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_a83428-7d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_a83428-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4433_a83428-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4433_a83428-7d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_a83428-7d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_a83428-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_a83428-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_a83428-7d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32, .wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32[data-kb-block=\"kb-adv-heading4433_b48be4-32\"]{display:block;font-size:35px;font-weight:500;font-style:normal;font-family:Poppins;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32[data-kb-block=\"kb-adv-heading4433_b48be4-32\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32[data-kb-block=\"kb-adv-heading4433_b48be4-32\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32, .wp-block-kadence-advancedheading.kt-adv-heading4433_b48be4-32[data-kb-block=\"kb-adv-heading4433_b48be4-32\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);font-size:25px;line-height:1.2;}}<\/style>\n<span class=\"kt-adv-heading4433_b48be4-32 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4433_b48be4-32\">services<\/span>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e, .wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e[data-kb-block=\"kb-adv-heading4433_1c975c-4e\"]{margin-top:-1px;font-size:var(--global-kb-font-size-xl, 3rem);font-weight:500;font-style:normal;font-family:Poppins;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e[data-kb-block=\"kb-adv-heading4433_1c975c-4e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e[data-kb-block=\"kb-adv-heading4433_1c975c-4e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e, .wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e[data-kb-block=\"kb-adv-heading4433_1c975c-4e\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e, .wp-block-kadence-advancedheading.kt-adv-heading4433_1c975c-4e[data-kb-block=\"kb-adv-heading4433_1c975c-4e\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h1 class=\"kt-adv-heading4433_1c975c-4e wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading4433_1c975c-4e\">\u00c9cologie et milieux naturels<\/h1>\n<\/div><\/div>\n\n\n<style>.kadence-column4433_a1331e-e4 > .kt-inside-inner-col,.kadence-column4433_a1331e-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_a1331e-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_a1331e-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4433_a1331e-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4433_a1331e-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_a1331e-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column4433_a1331e-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_a1331e-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_a1331e-e4\"><div class=\"kt-inside-inner-col\"><style>.kb-image4433_7b8cfe-1f .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;}.kb-image4433_7b8cfe-1f img.kb-img, .kb-image4433_7b8cfe-1f .kb-img img{border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4433_7b8cfe-1f size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"517\" src=\"https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2025\/07\/papillon-sur-eupatoire_reduite-3.jpeg\" alt=\"\" class=\"kb-img wp-image-5225\" title=\"\"><\/figure>\n<\/div><\/div>\n\n<\/div><\/section>\n\n<style>.kb-row-layout-id4433_e995ef-ea > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4433_e995ef-ea > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4433_e995ef-ea > .kt-row-column-wrap{column-gap:80px;row-gap:20px;max-width:var( --global-content-width, 1440px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4433_e995ef-ea > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4433_e995ef-ea > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4433_e995ef-ea > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id4433_e995ef-ea alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4433_f71689-37 > .kt-inside-inner-col,.kadence-column4433_f71689-37 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_f71689-37 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_f71689-37 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4433_f71689-37 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4433_f71689-37 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_f71689-37{position:relative;}@media all and (max-width: 1024px){.kadence-column4433_f71689-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_f71689-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_f71689-37 kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.kb-image4433_91aec4-7f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image4433_91aec4-7f size-full image-is-svg\"><img decoding=\"async\" src=\"https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2024\/07\/texture-gcm-jaune@3x.svg\" alt=\"\" class=\"kb-img wp-image-4351\" title=\"\"><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4433_cade1a-8f > .kt-inside-inner-col{display:flex;}.kadence-column4433_cade1a-8f > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xxl, 5rem);}.kadence-column4433_cade1a-8f > .kt-inside-inner-col,.kadence-column4433_cade1a-8f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_cade1a-8f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_cade1a-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_cade1a-8f > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4433_cade1a-8f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_cade1a-8f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_cade1a-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_cade1a-8f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_cade1a-8f{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4433_cade1a-8f{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_cade1a-8f{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_cade1a-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4433_cade1a-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_cade1a-8f > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column4433_cade1a-8f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_cade1a-8f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_cade1a-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_cade1a-8f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec, .wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec[data-kb-block=\"kb-adv-heading4433_8d8b7f-ec\"]{font-weight:600;font-style:normal;font-family:Poppins;}.wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec[data-kb-block=\"kb-adv-heading4433_8d8b7f-ec\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec[data-kb-block=\"kb-adv-heading4433_8d8b7f-ec\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec, .wp-block-kadence-advancedheading.kt-adv-heading4433_8d8b7f-ec[data-kb-block=\"kb-adv-heading4433_8d8b7f-ec\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h3 class=\"kt-adv-heading4433_8d8b7f-ec has-35-25-font-size wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading4433_8d8b7f-ec\">Mise en contexte<\/h3>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"font-size:18px\">Notre \u00e9quipe de biologistes et de professionnel.le.s en environnement vous offre des services sp\u00e9cialis\u00e9s pour \u00e9valuer et comprendre les \u00e9cosyst\u00e8mes dans lesquels s&rsquo;inscrivent vos projets.&nbsp;<\/p>\n<\/div><\/div>\n\n<\/div><\/section>\n\n<style>.kb-row-layout-id4433_b56d07-24 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4433_b56d07-24 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4433_b56d07-24 > .kt-row-column-wrap{column-gap:150px;max-width:var( --global-content-width, 1440px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-3xl, 6.5rem);grid-template-columns:minmax(0, calc(50% - ((150px * 1 )\/2)))minmax(0, calc(50% - ((150px * 1 )\/2)));}.kb-row-layout-id4433_b56d07-24{background-image:url('https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2024\/08\/tortue.webp');background-size:auto;background-position:50% 100%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id4433_b56d07-24 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4433_b56d07-24 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4433_b56d07-24 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id4433_b56d07-24 alignfull has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4433_b66f23-39 > .kt-inside-inner-col{display:flex;}.kadence-column4433_b66f23-39 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-5xl, 10rem);}.kadence-column4433_b66f23-39 > .kt-inside-inner-col,.kadence-column4433_b66f23-39 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_b66f23-39 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_b66f23-39 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column4433_b66f23-39 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4433_b66f23-39{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_b66f23-39{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_b66f23-39 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column4433_b66f23-39 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_b66f23-39{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4433_b66f23-39{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_b66f23-39{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_b66f23-39 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column4433_b66f23-39 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kadence-column4433_b66f23-39 > .kt-inside-inner-col{padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:flex-start;}.kt-row-column-wrap > .kadence-column4433_b66f23-39{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_b66f23-39{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_b66f23-39 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_b66f23-39\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2, .wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2[data-kb-block=\"kb-adv-heading4433_7bb87a-b2\"]{font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2[data-kb-block=\"kb-adv-heading4433_7bb87a-b2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2[data-kb-block=\"kb-adv-heading4433_7bb87a-b2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2, .wp-block-kadence-advancedheading.kt-adv-heading4433_7bb87a-b2[data-kb-block=\"kb-adv-heading4433_7bb87a-b2\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading4433_7bb87a-b2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4433_7bb87a-b2\">Cultivons la cr\u00e9ativit\u00e9 lors de l\u2019implantation de vos projets dans un nouvel \u00e9cosyst\u00e8me!<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column4433_abe31e-15 > .kt-inside-inner-col,.kadence-column4433_abe31e-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_abe31e-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_abe31e-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4433_abe31e-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4433_abe31e-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_abe31e-15{position:relative;}@media all and (max-width: 1024px){.kadence-column4433_abe31e-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_abe31e-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_abe31e-15 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.kadence-column4433_97b149-8c > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-xl, 4rem);}.kadence-column4433_97b149-8c > .kt-inside-inner-col{min-height:823px;}.kadence-column4433_97b149-8c > .kt-inside-inner-col,.kadence-column4433_97b149-8c > .kt-inside-inner-col:before{border-top-left-radius:45px;border-top-right-radius:45px;border-bottom-right-radius:45px;border-bottom-left-radius:45px;}.kadence-column4433_97b149-8c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_97b149-8c > .kt-inside-inner-col{flex-direction:column;}.kadence-column4433_97b149-8c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4433_97b149-8c > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column4433_97b149-8c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_97b149-8c{position:relative;}@media all and (max-width: 1024px){.kadence-column4433_97b149-8c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_97b149-8c > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);flex-direction:column;justify-content:center;}.kadence-column4433_97b149-8c, .kt-inside-inner-col > .kadence-column4433_97b149-8c:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_97b149-8c\"><div class=\"kt-inside-inner-col\"><style>.kadence-column4433_d7559a-ca > .kt-inside-inner-col{display:flex;}.kadence-column4433_d7559a-ca > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column4433_d7559a-ca > .kt-inside-inner-col{min-height:400px;}.kadence-column4433_d7559a-ca > .kt-inside-inner-col,.kadence-column4433_d7559a-ca > .kt-inside-inner-col:before{border-top-left-radius:45px;border-top-right-radius:45px;border-bottom-right-radius:45px;border-bottom-left-radius:45px;}.kadence-column4433_d7559a-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_d7559a-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_d7559a-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4433_d7559a-ca{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_d7559a-ca{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_d7559a-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_d7559a-ca > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column4433_d7559a-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_d7559a-ca{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4433_d7559a-ca{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_d7559a-ca{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_d7559a-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4433_d7559a-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_d7559a-ca > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column4433_d7559a-ca{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_d7559a-ca{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_d7559a-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_d7559a-ca\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e, .wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e[data-kb-block=\"kb-adv-heading4433_19cad7-2e\"]{padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);font-size:28px;line-height:1.3;font-weight:500;font-style:normal;font-family:Poppins;}.wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e[data-kb-block=\"kb-adv-heading4433_19cad7-2e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e[data-kb-block=\"kb-adv-heading4433_19cad7-2e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e, .wp-block-kadence-advancedheading.kt-adv-heading4433_19cad7-2e[data-kb-block=\"kb-adv-heading4433_19cad7-2e\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);font-size:23px;}}<\/style>\n<h3 class=\"kt-adv-heading4433_19cad7-2e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4433_19cad7-2e\">Des \u00e9tapes pr\u00e9liminaires de planification jusqu\u2019\u00e0 la surveillance et au suivi post projet, nous sommes fiers de vous offrir un service de proximit\u00e9 pour&nbsp;:<\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items4433_32f770-db:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items4433_32f770-db ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-iconlist.kt-svg-icon-list-items4433_32f770-db ul.kt-svg-icon-list{grid-row-gap:16px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items4433_32f770-db .kb-svg-icon-wrap{font-size:25px;color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items4433_32f770-db ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:17px;}.kt-svg-icon-list-items4433_32f770-db ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items4433_32f770-db kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-4433_e23617-ae .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4433_e23617-ae\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u00c9tude de caract\u00e9risation \u00e9cologique du milieu naturel (cours d\u2019eau, type de sols, etc.)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4433_c05724-af .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4433_c05724-af\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Inventaire floristique et faunique (micromammif\u00e8re, chiropt\u00e8re, avifaune, herp\u00e9tofaune, ichtyologie, etc.)&nbsp;<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4433_c698f2-6c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4433_c698f2-6c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Autorisations r\u00e9glementaires (municipal, provincial et f\u00e9d\u00e9ral) <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4433_02e3cd-17 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4433_02e3cd-17\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Caract\u00e9risation de l\u2019habitat du poisson<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4433_d61c28-a7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4433_d61c28-a7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u00c9valuation des impacts et mesures d\u2019att\u00e9nuation et de compensation <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4433_85e9d4-64 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4433_85e9d4-64\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Suivi environnemental sur vos sites (rapports et proposition de mesures correctives<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4433_dfe064-1d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4433_dfe064-1d\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Accompagnement dans vos initiatives d\u2019\u00e9valuation, de pr\u00e9servation et de r\u00e9tablissement de la biodiversit\u00e9&nbsp;<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/section>\n\n<style>.kb-row-layout-id4433_1fce58-c6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4433_1fce58-c6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4433_1fce58-c6 > .kt-row-column-wrap{column-gap:80px;row-gap:20px;max-width:var( --global-content-width, 1440px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4433_1fce58-c6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4433_1fce58-c6 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4433_1fce58-c6 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id4433_1fce58-c6 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4433_c3424e-0e > .kt-inside-inner-col{display:flex;}.kadence-column4433_c3424e-0e > .kt-inside-inner-col{min-height:186px;}.kadence-column4433_c3424e-0e > .kt-inside-inner-col,.kadence-column4433_c3424e-0e > .kt-inside-inner-col:before{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-column4433_c3424e-0e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_c3424e-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_c3424e-0e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4433_c3424e-0e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_c3424e-0e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_c3424e-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_c3424e-0e > .kt-inside-inner-col{background-color:var(--global-palette3, #1A202C);}.kadence-column4433_c3424e-0e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_c3424e-0e{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4433_c3424e-0e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_c3424e-0e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_c3424e-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4433_c3424e-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_c3424e-0e > .kt-inside-inner-col{min-height:300px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column4433_c3424e-0e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_c3424e-0e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_c3424e-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_c3424e-0e\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4433_e31ade-b0 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id4433_e31ade-b0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id4433_e31ade-b0 > .kt-row-column-wrap{column-gap:80px;row-gap:20px;max-width:var( --global-content-width, 1440px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(60% - ((80px * 1 )\/2)))minmax(0, calc(40% - ((80px * 1 )\/2)));}.kb-row-layout-id4433_e31ade-b0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4433_e31ade-b0 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4433_e31ade-b0 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-xs, 1rem);min-height:200px;grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id4433_e31ade-b0 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column4433_f48753-14 > .kt-inside-inner-col{padding-right:0px;padding-left:var(--global-kb-spacing-lg, 3rem);}.kadence-column4433_f48753-14 > .kt-inside-inner-col,.kadence-column4433_f48753-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_f48753-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_f48753-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4433_f48753-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4433_f48753-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_f48753-14{position:relative;}@media all and (max-width: 1024px){.kadence-column4433_f48753-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_f48753-14 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_f48753-14\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8, .wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8[data-kb-block=\"kb-adv-heading4433_7d0e16-a8\"]{display:block;font-size:var(--global-kb-font-size-lg, 2rem);line-height:1.2;font-style:normal;font-family:var( --global-body-font-family, inherit );text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8[data-kb-block=\"kb-adv-heading4433_7d0e16-a8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8[data-kb-block=\"kb-adv-heading4433_7d0e16-a8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8, .wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8[data-kb-block=\"kb-adv-heading4433_7d0e16-a8\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8, .wp-block-kadence-advancedheading.kt-adv-heading4433_7d0e16-a8[data-kb-block=\"kb-adv-heading4433_7d0e16-a8\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<span class=\"kt-adv-heading4433_7d0e16-a8 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading4433_7d0e16-a8\"><strong>Parlez-nous de votre projet<\/strong><\/span>\n<\/div><\/div>\n\n\n<style>.kadence-column4433_7faf38-3a > .kt-inside-inner-col{display:flex;}.kadence-column4433_7faf38-3a > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-lg, 3rem);}.kadence-column4433_7faf38-3a > .kt-inside-inner-col,.kadence-column4433_7faf38-3a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_7faf38-3a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_7faf38-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_7faf38-3a > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4433_7faf38-3a{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_7faf38-3a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_7faf38-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4433_7faf38-3a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_7faf38-3a{position:relative;}@media all and (max-width: 1024px){.kadence-column4433_7faf38-3a > .kt-inside-inner-col{padding-left:var(--global-kb-spacing-lg, 3rem);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4433_7faf38-3a{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_7faf38-3a{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_7faf38-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_7faf38-3a > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column4433_7faf38-3a{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_7faf38-3a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4433_7faf38-3a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_7faf38-3a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70, .wp-block-kadence-advancedbtn.kb-btns4433_1abe3f-70, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns4433_1abe3f-70{margin-top:0px;}.wp-block-kadence-advancedbtn.kb-btns4433_1abe3f-70{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-end;align-items:center;}.kt-btns4433_1abe3f-70 .kt-button{font-weight:normal;font-style:normal;}.kt-btns4433_1abe3f-70 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns4433_1abe3f-70 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns4433_1abe3f-70{justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns4433_1abe3f-70\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn4433_c18893-06.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn4433_c18893-06.kb-button{color:#000000;background:var(--global-palette2, #2B6CB0);}<\/style><a class=\"kb-button kt-button button kb-btn4433_c18893-06 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/www.gcmenvirosynergies.com\/contact\/\"><span class=\"kt-btn-inner-text\">Parlons-nous<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/section><\/div><\/div>\n\n<\/div><\/section>\n\n<style>.kb-row-layout-id4433_1a1493-1b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4433_1a1493-1b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4433_1a1493-1b > .kt-row-column-wrap{column-gap:80px;row-gap:20px;max-width:var( --global-content-width, 1440px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4433_1a1493-1b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4433_1a1493-1b > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4433_1a1493-1b > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id4433_1a1493-1b alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4433_f637d4-e6 > .kt-inside-inner-col,.kadence-column4433_f637d4-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4433_f637d4-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4433_f637d4-e6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4433_f637d4-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4433_f637d4-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4433_f637d4-e6{position:relative;}@media all and (max-width: 1024px){.kadence-column4433_f637d4-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4433_f637d4-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4433_f637d4-e6\"><div class=\"kt-inside-inner-col\"><!-- [element-1345] --><style>.kb-row-layout-id1345_503e08-96 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1345_503e08-96 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1345_503e08-96 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1440px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1345_503e08-96 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1345_503e08-96 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1345_503e08-96 > .kt-row-column-wrap{padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><section class=\"kb-row-layout-wrap kb-row-layout-id1345_503e08-96 alignfull has-theme-palette9-background-color kt-row-has-bg cards wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col,.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col{column-gap:20px;}.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_ff4f7b-05{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_ff4f7b-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_ff4f7b-05 kb-section-dir-vertical kb-section-sm-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1345_f5a599-4d > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1345_f5a599-4d > .kt-inside-inner-col{min-height:400px;border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);}.kadence-column1345_f5a599-4d > .kt-inside-inner-col,.kadence-column1345_f5a599-4d > .kt-inside-inner-col:before{border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;}.kadence-column1345_f5a599-4d:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}.kadence-column1345_f5a599-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_f5a599-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_f5a599-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_f5a599-4d:hover > .kt-inside-inner-col{background-color:var(--global-palette2, #2B6CB0);background-image:none;}.kadence-column1345_f5a599-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_f5a599-4d{position:relative;}.kadence-column1345_f5a599-4d, .kt-inside-inner-col > .kadence-column1345_f5a599-4d:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1345_f5a599-4d > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1345_f5a599-4d:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kadence-column1345_f5a599-4d > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kadence-column1345_f5a599-4d:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_f5a599-4d kb-section-has-link card\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1345_535841-b5 > .kt-inside-inner-col,.kadence-column1345_535841-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_535841-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_535841-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_535841-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_535841-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_535841-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_535841-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_535841-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_535841-b5\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"94\" height=\"108\" src=\"https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2023\/08\/icon-Etudes-et-autorisations@2x.png\" alt=\"\u00c9tudes et autorisations\" class=\"wp-image-4009\" style=\"width:47px\" title=\"\"><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c, .wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c[data-kb-block=\"kb-adv-heading1345_0bc7df-3c\"]{margin-top:var(--global-kb-spacing-md, 2rem);font-size:32px;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c[data-kb-block=\"kb-adv-heading1345_0bc7df-3c\"] mark.kt-highlight{font-size:21px;font-style:normal;color:rgba(113,128,150,0.5);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c[data-kb-block=\"kb-adv-heading1345_0bc7df-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c, .wp-block-kadence-advancedheading.kt-adv-heading1345_0bc7df-3c[data-kb-block=\"kb-adv-heading1345_0bc7df-3c\"]{font-size:32px;}}<\/style>\n<h3 class=\"kt-adv-heading1345_0bc7df-3c wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1345_0bc7df-3c\">\u00c9tudes et autorisations environnementales<\/h3>\n<\/div><\/div>\n\n\n<style>.kadence-column1345_abb8b3-2b > .kt-inside-inner-col,.kadence-column1345_abb8b3-2b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_abb8b3-2b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_abb8b3-2b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_abb8b3-2b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_abb8b3-2b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_abb8b3-2b{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_abb8b3-2b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_abb8b3-2b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_abb8b3-2b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1345_109549-ee{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1345_109549-ee .kt-button{font-weight:normal;font-style:normal;}.kt-btns1345_109549-ee .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1345_109549-ee .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1345_109549-ee .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_109549-ee .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1345_109549-ee .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1345_109549-ee .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_109549-ee .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1345_109549-ee\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1345_19006a-ce.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1345_19006a-ce.kb-button{color:#000000;background:rgba(0,0,0,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:var(--global-kb-spacing-md, 2rem);}.wp-block-kadence-advancedbtn .kb-btn1345_19006a-ce.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1345_19006a-ce.kb-button:focus{color:#000000;background:rgba(0,0,0,0.02);}<\/style><a class=\"kb-button kt-button button kb-btn1345_19006a-ce kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/www.gcmenvirosynergies.com\/services\/etudes-et-autorisations-environnementales\/\"><span class=\"kt-btn-inner-text\">En savoir plus<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><a href=\"https:\/\/www.gcmenvirosynergies.com\/services\/etudes-et-autorisations-environnementales\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1345_849cb1-d7 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1345_849cb1-d7 > .kt-inside-inner-col{min-height:400px;border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);}.kadence-column1345_849cb1-d7 > .kt-inside-inner-col,.kadence-column1345_849cb1-d7 > .kt-inside-inner-col:before{border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;}.kadence-column1345_849cb1-d7:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}.kadence-column1345_849cb1-d7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_849cb1-d7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_849cb1-d7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_849cb1-d7:hover > .kt-inside-inner-col{background-color:var(--global-palette2, #2B6CB0);background-image:none;}.kadence-column1345_849cb1-d7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_849cb1-d7{position:relative;}.kadence-column1345_849cb1-d7, .kt-inside-inner-col > .kadence-column1345_849cb1-d7:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1345_849cb1-d7 > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1345_849cb1-d7:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kadence-column1345_849cb1-d7 > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kadence-column1345_849cb1-d7:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_849cb1-d7 kb-section-has-link card\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1345_83313c-35 > .kt-inside-inner-col,.kadence-column1345_83313c-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_83313c-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_83313c-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_83313c-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_83313c-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_83313c-35{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_83313c-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_83313c-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_83313c-35\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"108\" src=\"https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2023\/08\/icon-Ecologie-et-milieux-naturels@2x.png\" alt=\"\u00c9cologie et milieux naturels\" class=\"wp-image-4014\" style=\"width:56px\" title=\"\"><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1345_d9d1ff-58, .wp-block-kadence-advancedheading.kt-adv-heading1345_d9d1ff-58[data-kb-block=\"kb-adv-heading1345_d9d1ff-58\"]{margin-top:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1345_d9d1ff-58 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1345_d9d1ff-58[data-kb-block=\"kb-adv-heading1345_d9d1ff-58\"] mark.kt-highlight{font-size:21px;font-style:normal;color:rgba(113,128,150,0.5);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1345_d9d1ff-58 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1345_d9d1ff-58[data-kb-block=\"kb-adv-heading1345_d9d1ff-58\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1345_d9d1ff-58 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1345_d9d1ff-58\">\u00c9cologie et milieux naturels<\/h3>\n<\/div><\/div>\n\n\n<style>.kadence-column1345_239916-93 > .kt-inside-inner-col,.kadence-column1345_239916-93 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_239916-93 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_239916-93 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_239916-93 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_239916-93 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_239916-93{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_239916-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_239916-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_239916-93\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1345_7621ff-1b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1345_7621ff-1b .kt-button{font-weight:normal;font-style:normal;}.kt-btns1345_7621ff-1b .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1345_7621ff-1b .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1345_7621ff-1b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_7621ff-1b .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1345_7621ff-1b .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1345_7621ff-1b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_7621ff-1b .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1345_7621ff-1b\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1345_d23cec-f1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1345_d23cec-f1.kb-button{color:#000000;background:rgba(0,0,0,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:var(--global-kb-spacing-md, 2rem);}<\/style><span class=\"kb-button kt-button button kb-btn1345_d23cec-f1 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">En savoir plus<\/span><\/span><\/div>\n<\/div><\/div>\n<\/div><a href=\"https:\/\/www.gcmenvirosynergies.com\/services\/ecologie-et-milieux-naturels\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1345_d87438-13 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1345_d87438-13 > .kt-inside-inner-col{min-height:400px;border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);}.kadence-column1345_d87438-13 > .kt-inside-inner-col,.kadence-column1345_d87438-13 > .kt-inside-inner-col:before{border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;}.kadence-column1345_d87438-13:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}.kadence-column1345_d87438-13 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_d87438-13 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_d87438-13 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_d87438-13:hover > .kt-inside-inner-col{background-color:var(--global-palette2, #2B6CB0);background-image:none;}.kadence-column1345_d87438-13 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_d87438-13{position:relative;}.kadence-column1345_d87438-13, .kt-inside-inner-col > .kadence-column1345_d87438-13:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1345_d87438-13 > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1345_d87438-13:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kadence-column1345_d87438-13 > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kadence-column1345_d87438-13:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_d87438-13 kb-section-has-link card\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col,.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_a7f9ef-61{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_a7f9ef-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_a7f9ef-61\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"86\" height=\"106\" src=\"https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2023\/08\/icon-Traitement-des-eaux-industrielles@2x.png\" alt=\"Traitement des eaux industrielles et gestion des eaux de surface\" class=\"wp-image-4016\" style=\"width:43px\" title=\"\"><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1345_c59a97-a6, .wp-block-kadence-advancedheading.kt-adv-heading1345_c59a97-a6[data-kb-block=\"kb-adv-heading1345_c59a97-a6\"]{margin-top:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1345_c59a97-a6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1345_c59a97-a6[data-kb-block=\"kb-adv-heading1345_c59a97-a6\"] mark.kt-highlight{font-size:21px;font-style:normal;color:rgba(113,128,150,0.5);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1345_c59a97-a6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1345_c59a97-a6[data-kb-block=\"kb-adv-heading1345_c59a97-a6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1345_c59a97-a6 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1345_c59a97-a6\">Traitement des eaux industrielles et gestion des eaux de surface<\/h3>\n<\/div><\/div>\n\n\n<style>.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col,.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_35f7eb-b7{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_35f7eb-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_35f7eb-b7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1345_781049-31{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1345_781049-31 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1345_781049-31 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1345_781049-31 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1345_781049-31 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_781049-31 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1345_781049-31 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1345_781049-31 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_781049-31 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1345_781049-31\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1345_c8062c-e6.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1345_c8062c-e6.kb-button{color:var(--global-palette3, #1A202C);background:rgba(0,0,0,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:var(--global-kb-spacing-md, 2rem);}.wp-block-kadence-advancedbtn .kb-btn1345_c8062c-e6.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1345_c8062c-e6.kb-button:focus{background:rgba(0,0,0,0.02);}<\/style><span class=\"kb-button kt-button button kb-btn1345_c8062c-e6 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">En savoir plus<\/span><\/span><\/div>\n<\/div><\/div>\n<\/div><a href=\"https:\/\/www.gcmenvirosynergies.com\/services\/traitement-des-eaux-industrielles-et-gestion-des-eaux-de-surface\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1345_5c7979-2e > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1345_5c7979-2e > .kt-inside-inner-col{min-height:400px;border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);}.kadence-column1345_5c7979-2e > .kt-inside-inner-col,.kadence-column1345_5c7979-2e > .kt-inside-inner-col:before{border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;}.kadence-column1345_5c7979-2e:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}.kadence-column1345_5c7979-2e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_5c7979-2e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_5c7979-2e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_5c7979-2e:hover > .kt-inside-inner-col{background-color:var(--global-palette2, #2B6CB0);background-image:none;}.kadence-column1345_5c7979-2e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_5c7979-2e{position:relative;}.kadence-column1345_5c7979-2e, .kt-inside-inner-col > .kadence-column1345_5c7979-2e:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1345_5c7979-2e > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1345_5c7979-2e:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kadence-column1345_5c7979-2e > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kadence-column1345_5c7979-2e:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_5c7979-2e kb-section-has-link card\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col,.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_dd9ca1-14{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_dd9ca1-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_dd9ca1-14\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"108\" src=\"https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2023\/08\/icon-Traitement-des-eaux-sanitaires@2x.png\" alt=\"Traitement des eaux sanitaires et potables\" class=\"wp-image-4012\" style=\"width:56px\" title=\"\"><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1345_a85ee1-ac, .wp-block-kadence-advancedheading.kt-adv-heading1345_a85ee1-ac[data-kb-block=\"kb-adv-heading1345_a85ee1-ac\"]{margin-top:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1345_a85ee1-ac mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1345_a85ee1-ac[data-kb-block=\"kb-adv-heading1345_a85ee1-ac\"] mark.kt-highlight{font-size:21px;font-style:normal;color:rgba(113,128,150,0.5);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1345_a85ee1-ac img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1345_a85ee1-ac[data-kb-block=\"kb-adv-heading1345_a85ee1-ac\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1345_a85ee1-ac wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1345_a85ee1-ac\">Traitement des eaux sanitaires et potables<\/h3>\n<\/div><\/div>\n\n\n<style>.kadence-column1345_c95042-bb > .kt-inside-inner-col,.kadence-column1345_c95042-bb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_c95042-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_c95042-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_c95042-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_c95042-bb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_c95042-bb{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_c95042-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_c95042-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_c95042-bb\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1345_c90dec-71{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1345_c90dec-71 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1345_c90dec-71 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1345_c90dec-71 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1345_c90dec-71 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_c90dec-71 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1345_c90dec-71 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1345_c90dec-71 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_c90dec-71 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1345_c90dec-71\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1345_6d2db8-81.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1345_6d2db8-81.kb-button{background:rgba(0,0,0,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:var(--global-kb-spacing-md, 2rem);}<\/style><span class=\"kb-button kt-button button kb-btn1345_6d2db8-81 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">En savoir plus<\/span><\/span><\/div>\n<\/div><\/div>\n<\/div><a href=\"https:\/\/www.gcmenvirosynergies.com\/services\/traitement-des-eaux-sanitaires-et-potables\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column1345_8c6706-0f > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1345_8c6706-0f > .kt-inside-inner-col{min-height:400px;border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);}.kadence-column1345_8c6706-0f > .kt-inside-inner-col,.kadence-column1345_8c6706-0f > .kt-inside-inner-col:before{border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;}.kadence-column1345_8c6706-0f:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}.kadence-column1345_8c6706-0f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_8c6706-0f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_8c6706-0f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_8c6706-0f:hover > .kt-inside-inner-col{background-color:var(--global-palette2, #2B6CB0);background-image:none;}.kadence-column1345_8c6706-0f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_8c6706-0f{position:relative;}.kadence-column1345_8c6706-0f, .kt-inside-inner-col > .kadence-column1345_8c6706-0f:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1345_8c6706-0f > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1345_8c6706-0f:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kadence-column1345_8c6706-0f > .kt-inside-inner-col{border-top:2px solid var(--global-palette3, #1A202C);border-right:2px solid var(--global-palette3, #1A202C);border-bottom:2px solid var(--global-palette3, #1A202C);border-left:2px solid var(--global-palette3, #1A202C);flex-direction:column;justify-content:center;}.kadence-column1345_8c6706-0f:hover > .kt-inside-inner-col{border-top:2px solid var(--global-palette2, #2B6CB0);border-right:2px solid var(--global-palette2, #2B6CB0);border-bottom:2px solid var(--global-palette2, #2B6CB0);border-left:2px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_8c6706-0f kb-section-has-link card\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1345_8fcc73-1b > .kt-inside-inner-col,.kadence-column1345_8fcc73-1b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_8fcc73-1b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_8fcc73-1b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_8fcc73-1b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_8fcc73-1b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_8fcc73-1b{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_8fcc73-1b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_8fcc73-1b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_8fcc73-1b\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"108\" src=\"https:\/\/www.gcmenvirosynergies.com\/wp-content\/uploads\/2023\/08\/icon-Developpement-durable@2x.png\" alt=\"D\u00e9veloppement durable, d\u00e9carbonation et efficacit\u00e9 \u00e9nerg\u00e9tique\" class=\"wp-image-4018\" style=\"width:56px\" title=\"\"><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1345_ea7c10-e7, .wp-block-kadence-advancedheading.kt-adv-heading1345_ea7c10-e7[data-kb-block=\"kb-adv-heading1345_ea7c10-e7\"]{margin-top:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1345_ea7c10-e7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1345_ea7c10-e7[data-kb-block=\"kb-adv-heading1345_ea7c10-e7\"] mark.kt-highlight{font-size:21px;font-style:normal;color:rgba(113,128,150,0.5);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1345_ea7c10-e7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1345_ea7c10-e7[data-kb-block=\"kb-adv-heading1345_ea7c10-e7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1345_ea7c10-e7 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1345_ea7c10-e7\">D\u00e9veloppement durable, d\u00e9carbonation et efficacit\u00e9 \u00e9nerg\u00e9tique<\/h3>\n<\/div><\/div>\n\n\n<style>.kadence-column1345_bdd973-a1 > .kt-inside-inner-col,.kadence-column1345_bdd973-a1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1345_bdd973-a1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1345_bdd973-a1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1345_bdd973-a1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1345_bdd973-a1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1345_bdd973-a1{position:relative;}@media all and (max-width: 1024px){.kadence-column1345_bdd973-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1345_bdd973-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1345_bdd973-a1 kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1345_86af01-d0{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1345_86af01-d0 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1345_86af01-d0 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1345_86af01-d0 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1345_86af01-d0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_86af01-d0 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1345_86af01-d0 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1345_86af01-d0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1345_86af01-d0 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1345_86af01-d0\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1345_1d93cd-20.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1345_1d93cd-20.kb-button{background:rgba(0,0,0,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:var(--global-kb-spacing-md, 2rem);}<\/style><span class=\"kb-button kt-button button kb-btn1345_1d93cd-20 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">En savoir plus<\/span><\/span><\/div>\n<\/div><\/div>\n<\/div><a href=\"https:\/\/www.gcmenvirosynergies.com\/services\/developpement-durable-decarbonation-et-efficacite-energique\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/section><!-- [\/element-1345] -->\n<\/div><\/div>\n\n<\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>services \u00c9cologie et milieux naturels Mise en contexte Notre \u00e9quipe de biologistes et de professionnel.le.s en environnement vous offre des services sp\u00e9cialis\u00e9s pour \u00e9valuer et comprendre les \u00e9cosyst\u00e8mes dans lesquels s&rsquo;inscrivent vos projets.&nbsp; Cultivons la cr\u00e9ativit\u00e9 lors de l\u2019implantation de vos projets dans un nouvel \u00e9cosyst\u00e8me! Des \u00e9tapes pr\u00e9liminaires de planification jusqu\u2019\u00e0 la surveillance et&#8230;<\/p>","protected":false},"author":30,"featured_media":0,"parent":1559,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-4433","page","type-page","status-publish","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"maryse","author_link":"https:\/\/www.gcmenvirosynergies.com\/en\/author\/maryse\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/pages\/4433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/comments?post=4433"}],"version-history":[{"count":0,"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/pages\/4433\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/pages\/1559"}],"wp:attachment":[{"href":"https:\/\/www.gcmenvirosynergies.com\/en\/wp-json\/wp\/v2\/media?parent=4433"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}